{"id":926,"date":"2020-10-19T16:48:40","date_gmt":"2020-10-19T22:48:40","guid":{"rendered":"https:\/\/coombudsman.wpengine.com\/informes-anuales\/"},"modified":"2020-10-19T16:48:40","modified_gmt":"2020-10-19T22:48:40","slug":"informes-anuales","status":"publish","type":"page","link":"https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/","title":{"rendered":"Informes anuales"},"content":{"rendered":"<p>La Ley de Estadounidenses de Edad Avanzada exige que los defensores del pueblo de atenci\u00f3n a largo plazo del estado elaboren un informe de las actividades del programa en nombre de los residentes. Este informe se presenta anualmente a la Administraci\u00f3n para la Vida Comunitaria (Administration for Community Living, ACL) y se pone a disposici\u00f3n del p\u00fablico aqu\u00ed. <span style=\"color: #000080\"><strong>Atenci\u00f3n a largo plazo (Long-Term Care, LTC)<\/strong><\/span> <\/p>\n<ul>\n<li><a href=\"https:\/\/www.coombudsman.org\/wp-content\/uploads\/2022\/05\/2021-Annual-Report.pdf\">Informe anual de 2021<\/a><\/li>\n<li><a href=\"https:\/\/www.coombudsman.org\/wp-content\/uploads\/2021\/03\/2020-Annual-Report.pdf\">Informe anual de 2020<\/a><\/li>\n<li><a href=\"https:\/\/www.coombudsman.org\/wp-content\/uploads\/2021\/01\/2019-Annual-Report.pdf\">Informe anual de 2019<\/a><\/li>\n<li><a href=\"https:\/\/www.coombudsman.org\/wp-content\/uploads\/2021\/01\/2018-Annual-Report-1.pdf\">Informe anual de 2018<\/a><\/li>\n<li><a href=\"https:\/\/www.coombudsman.org\/wp-content\/uploads\/2021\/01\/2017-Annual-Report.pdf\">Informe anual de 2017<\/a><\/li>\n<\/ul>\n<p> <span style=\"color: #000080\"><strong>Programas de atenci\u00f3n integral para personas mayores (Programs of All-Inclusive Care for the Elderly, PACE)<\/strong><\/span> <\/p>\n<ul>\n<li><a href=\"https:\/\/www.coombudsman.org\/wp-content\/uploads\/2022\/05\/PACE-Annual-Report-2021.pdf\">Informe anual de 2021<\/a><\/li>\n<\/ul>\n<p> <span style=\"color: #000080\"><strong>Desarrollador de asistencia legal<\/strong><\/span> <\/p>\n<ul>\n<li><a href=\"https:\/\/www.coombudsman.org\/wp-content\/uploads\/2022\/05\/Colorado-Legal-Assistance-Developer-2021-Annual-Report.pdf\">Informe anual de 2021<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La Ley de Estadounidenses de Edad Avanzada exige que los defensores del pueblo de atenci\u00f3n a largo plazo del estado elaboren un informe de las actividades del programa en nombre de los residentes. Este informe se presenta anualmente a la Administraci\u00f3n para la Vida Comunitaria (Administration for Community Living, ACL) y se pone a disposici\u00f3n&#8230; <a class=\"read-more\" href=\"https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/\">Read More<\/a><\/p>\n","protected":false},"author":15,"featured_media":0,"parent":929,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-926","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informes anuales - Programa del defensor del pueblo de atenci\u00f3n a largo plazo del estado de Colorado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informes anuales - Programa del defensor del pueblo de atenci\u00f3n a largo plazo del estado de Colorado\" \/>\n<meta property=\"og:description\" content=\"La Ley de Estadounidenses de Edad Avanzada exige que los defensores del pueblo de atenci\u00f3n a largo plazo del estado elaboren un informe de las actividades del programa en nombre de los residentes. Este informe se presenta anualmente a la Administraci\u00f3n para la Vida Comunitaria (Administration for Community Living, ACL) y se pone a disposici\u00f3n... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa del defensor del pueblo de atenci\u00f3n a largo plazo del estado de Colorado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.coombudsman.org\\\/es\\\/recursos\\\/informes-anuales\\\/\",\"url\":\"https:\\\/\\\/www.coombudsman.org\\\/es\\\/recursos\\\/informes-anuales\\\/\",\"name\":\"Informes anuales - Programa del defensor del pueblo de atenci\u00f3n a largo plazo del estado de Colorado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coombudsman.org\\\/#website\"},\"datePublished\":\"2020-10-19T22:48:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.coombudsman.org\\\/es\\\/recursos\\\/informes-anuales\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.coombudsman.org\\\/es\\\/recursos\\\/informes-anuales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.coombudsman.org\\\/es\\\/recursos\\\/informes-anuales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.coombudsman.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recursos\",\"item\":\"https:\\\/\\\/www.coombudsman.org\\\/es\\\/recursos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Informes anuales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.coombudsman.org\\\/#website\",\"url\":\"https:\\\/\\\/www.coombudsman.org\\\/\",\"name\":\"Programa del defensor del pueblo de atenci\u00f3n a largo plazo del estado de Colorado\",\"description\":\"Colorado LTC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.coombudsman.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informes anuales - Programa del defensor del pueblo de atenci\u00f3n a largo plazo del estado de Colorado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/","og_locale":"es_ES","og_type":"article","og_title":"Informes anuales - Programa del defensor del pueblo de atenci\u00f3n a largo plazo del estado de Colorado","og_description":"La Ley de Estadounidenses de Edad Avanzada exige que los defensores del pueblo de atenci\u00f3n a largo plazo del estado elaboren un informe de las actividades del programa en nombre de los residentes. Este informe se presenta anualmente a la Administraci\u00f3n para la Vida Comunitaria (Administration for Community Living, ACL) y se pone a disposici\u00f3n... Read More","og_url":"https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/","og_site_name":"Programa del defensor del pueblo de atenci\u00f3n a largo plazo del estado de Colorado","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/","url":"https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/","name":"Informes anuales - Programa del defensor del pueblo de atenci\u00f3n a largo plazo del estado de Colorado","isPartOf":{"@id":"https:\/\/www.coombudsman.org\/#website"},"datePublished":"2020-10-19T22:48:40+00:00","breadcrumb":{"@id":"https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.coombudsman.org\/es\/recursos\/informes-anuales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.coombudsman.org\/es\/"},{"@type":"ListItem","position":2,"name":"Recursos","item":"https:\/\/www.coombudsman.org\/es\/recursos\/"},{"@type":"ListItem","position":3,"name":"Informes anuales"}]},{"@type":"WebSite","@id":"https:\/\/www.coombudsman.org\/#website","url":"https:\/\/www.coombudsman.org\/","name":"Programa del defensor del pueblo de atenci\u00f3n a largo plazo del estado de Colorado","description":"Colorado LTC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coombudsman.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/www.coombudsman.org\/es\/wp-json\/wp\/v2\/pages\/926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coombudsman.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.coombudsman.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.coombudsman.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coombudsman.org\/es\/wp-json\/wp\/v2\/comments?post=926"}],"version-history":[{"count":0,"href":"https:\/\/www.coombudsman.org\/es\/wp-json\/wp\/v2\/pages\/926\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.coombudsman.org\/es\/wp-json\/wp\/v2\/pages\/929"}],"wp:attachment":[{"href":"https:\/\/www.coombudsman.org\/es\/wp-json\/wp\/v2\/media?parent=926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}